{"id":9864,"date":"2023-02-18T19:45:47","date_gmt":"2023-02-18T18:45:47","guid":{"rendered":"https:\/\/www.ladiagonale.net\/?p=9864"},"modified":"2023-03-06T17:03:02","modified_gmt":"2023-03-06T16:03:02","slug":"le-groupe-monegasque-diop-convoque","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/","title":{"rendered":"Le groupe mon\u00e9gasque : Diop convoqu\u00e9"},"content":{"rendered":"\n<p>Philippe Clement doit faire face \u00e0 une cascade de blessures pour le d\u00e9placement \u00e0 Brest. Aguilar, Maripan, Vanderson, Volland et Gelson Martin sont \u00e0 l\u2019infirmerie pour cette rencontre. <\/p>\n\n\n\n<p>C\u2019est le couloir droit qui devrait donner le plus de tracas \u00e0 l\u2019entra\u00eeneur belge, qui a convoqu\u00e9 le jeune Edan Diop pour pallier les nombreux forfaits. M\u00eame s\u2019il \u00e9volue comme milieu de terrain, Philippe Clement l\u2019avait d\u00e9j\u00e0 test\u00e9 au poste de lat\u00e9ral droit contre Empoli.<\/p>\n\n\n\n<ul>\n\n<li><strong>Gardiens :<\/strong>&nbsp;Didillon, Lienard, N\u00fcbel.<\/li>\n\n\n<li><strong>D\u00e9fenseurs :<\/strong> C. Henrique, Disasi, Jakobs, Matsima, Okou, Sarr.<\/li>\n\n\n<li><strong>Milieux :<\/strong> Akliouche, Ben Seghir, Camara, Diatta, Diop, Fofana, Golovin, Magassa, Matazo, Minamino.<\/li>\n\n\n<li><strong>Attaquants :<\/strong> Ben Yedder, Boadu, Embolo.<\/li>\n\n<\/ul>\n\n\n\n<p><em>Absents :<\/em> Aguilar (blessure), Maripan, Vanderson (reprise), G. Martins, Volland (g\u00eane), J. Lucas (choix).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Philippe Clement doit faire face \u00e0 une cascade de blessures pour le d\u00e9placement \u00e0 Brest. Aguilar, Maripan, Vanderson, Volland et Gelson Martin sont \u00e0 l\u2019infirmerie pour cette rencontre. C\u2019est le couloir droit qui devrait donner le plus de tracas \u00e0 l\u2019entra\u00eeneur belge, qui a convoqu\u00e9 le jeune Edan Diop pour pallier les nombreux forfaits. M\u00eame [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[4,6],"tags":[86,373,225,94],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Philippe Clement doit faire face \u00e0 une cascade de blessures pour le d\u00e9placement \u00e0 Brest. Aguilar, Maripan, Vanderson, Volland et Gelson Martin sont \u00e0 l\u2019infirmerie pour cette rencontre. C\u2019est le couloir droit qui devrait donner le plus de tracas \u00e0 l\u2019entra\u00eeneur belge, qui a convoqu\u00e9 le jeune Edan Diop pour pallier les nombreux forfaits. M\u00eame [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-18T18:45:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T16:03:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/edan-diop.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1160\" \/>\n\t<meta property=\"og:image:height\" content=\"650\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/edan-diop.png\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/\",\"name\":\"Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2023-02-18T18:45:47+00:00\",\"dateModified\":\"2023-03-06T16:03:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le groupe mon\u00e9gasque : Diop convoqu\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/","og_locale":"fr_FR","og_type":"article","og_title":"Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale","og_description":"Philippe Clement doit faire face \u00e0 une cascade de blessures pour le d\u00e9placement \u00e0 Brest. Aguilar, Maripan, Vanderson, Volland et Gelson Martin sont \u00e0 l\u2019infirmerie pour cette rencontre. C\u2019est le couloir droit qui devrait donner le plus de tracas \u00e0 l\u2019entra\u00eeneur belge, qui a convoqu\u00e9 le jeune Edan Diop pour pallier les nombreux forfaits. M\u00eame [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/","og_site_name":"La Diagonale","article_published_time":"2023-02-18T18:45:47+00:00","article_modified_time":"2023-03-06T16:03:02+00:00","og_image":[{"width":1160,"height":650,"url":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/edan-diop.png","type":"image\/png"}],"author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.ladiagonale.net\/wp-content\/uploads\/2022\/12\/edan-diop.png","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/","name":"Le groupe mon\u00e9gasque : Diop convoqu\u00e9 - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2023-02-18T18:45:47+00:00","dateModified":"2023-03-06T16:03:02+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2023\/02\/18\/le-groupe-monegasque-diop-convoque\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Le groupe mon\u00e9gasque : Diop convoqu\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9864"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=9864"}],"version-history":[{"count":6,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9864\/revisions"}],"predecessor-version":[{"id":10460,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/9864\/revisions\/10460"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=9864"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=9864"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=9864"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}