{"id":990,"date":"2022-04-22T15:16:47","date_gmt":"2022-04-22T13:16:47","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/"},"modified":"2022-07-26T14:20:29","modified_gmt":"2022-07-26T12:20:29","slug":"newcastle-ne-lache-pas-badiashile","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/","title":{"rendered":"Newcastle ne l\u00e2che pas Badiashile"},"content":{"rendered":"<p>Cet hiver, Newcastle s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s insistant pour signer Beno\u00eet Badiashile et pourrait revenir \u00e0 la charge pour enr\u00f4ler le d\u00e9fenseur central de l&rsquo;AS Monaco cet \u00e9t\u00e9. Selon *Foot Mercato*, il faudrait d\u00e9bourser au moins 40 millions d&rsquo;euros pour convaincre le club de la Principaut\u00e9. Dans une situation compliqu\u00e9 \u00e0 la mi-saison, les *Magpies* ont redress\u00e9 la situation pour s&rsquo;installer en milieu de tableau et sont quasi assur\u00e9s de continuer en *Premier League* l&rsquo;an prochain.<\/p>\n<p>Il y a quelques jours, la [Juventus \u00e9tait \u00e9galement en Principaut\u00e9](https:\/\/www.ladiagonale.net\/news-1176-la-juventus-negocierait-pour-badiashile) par l&rsquo;interm\u00e9diaire de son directeur sportif, Federico Cherubini, pour n\u00e9gocier pour le joueur form\u00e9 au club. Une offre de 30 millions \u00e9tait \u00e9voqu\u00e9e. Mais l&rsquo;int\u00e9r\u00eat combin\u00e9 de plusieurs clubs devrait logiquement faire grimper les ench\u00e8res pour un joueur courtis\u00e9 en Europe depuis plusieurs ann\u00e9es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cet hiver, Newcastle s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s insistant pour signer Beno\u00eet Badiashile et pourrait revenir \u00e0 la charge pour enr\u00f4ler le d\u00e9fenseur central de l&rsquo;AS Monaco cet \u00e9t\u00e9. Selon *Foot Mercato*, il faudrait d\u00e9bourser au moins 40 millions d&rsquo;euros pour convaincre le club de la Principaut\u00e9. Dans une situation compliqu\u00e9 \u00e0 la mi-saison, les *Magpies* ont [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Newcastle ne l\u00e2che pas Badiashile - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Newcastle ne l\u00e2che pas Badiashile - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"Cet hiver, Newcastle s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s insistant pour signer Beno\u00eet Badiashile et pourrait revenir \u00e0 la charge pour enr\u00f4ler le d\u00e9fenseur central de l&rsquo;AS Monaco cet \u00e9t\u00e9. Selon *Foot Mercato*, il faudrait d\u00e9bourser au moins 40 millions d&rsquo;euros pour convaincre le club de la Principaut\u00e9. Dans une situation compliqu\u00e9 \u00e0 la mi-saison, les *Magpies* ont [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-22T13:16:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:29+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/\",\"name\":\"Newcastle ne l\u00e2che pas Badiashile - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-22T13:16:47+00:00\",\"dateModified\":\"2022-07-26T12:20:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Newcastle ne l\u00e2che pas Badiashile\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Newcastle ne l\u00e2che pas Badiashile - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/","og_locale":"fr_FR","og_type":"article","og_title":"Newcastle ne l\u00e2che pas Badiashile - La Diagonale","og_description":"Cet hiver, Newcastle s&rsquo;\u00e9tait montr\u00e9 tr\u00e8s insistant pour signer Beno\u00eet Badiashile et pourrait revenir \u00e0 la charge pour enr\u00f4ler le d\u00e9fenseur central de l&rsquo;AS Monaco cet \u00e9t\u00e9. Selon *Foot Mercato*, il faudrait d\u00e9bourser au moins 40 millions d&rsquo;euros pour convaincre le club de la Principaut\u00e9. Dans une situation compliqu\u00e9 \u00e0 la mi-saison, les *Magpies* ont [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/","og_site_name":"La Diagonale","article_published_time":"2022-04-22T13:16:47+00:00","article_modified_time":"2022-07-26T12:20:29+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/","name":"Newcastle ne l\u00e2che pas Badiashile - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-22T13:16:47+00:00","dateModified":"2022-07-26T12:20:29+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/newcastle-ne-lache-pas-badiashile\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Newcastle ne l\u00e2che pas Badiashile"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/990"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=990"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions"}],"predecessor-version":[{"id":1824,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/990\/revisions\/1824"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=990"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=990"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=990"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}