{"id":992,"date":"2022-04-22T19:07:57","date_gmt":"2022-04-22T17:07:57","guid":{"rendered":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/"},"modified":"2022-07-26T14:20:28","modified_gmt":"2022-07-26T12:20:28","slug":"disasi-notre-serie-donne-raison-au-coach","status":"publish","type":"post","link":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/","title":{"rendered":"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb"},"content":{"rendered":"<p>L\u2019AS Monaco se d\u00e9place \u00e0 Saint-\u00c9tienne ce samedi avec l\u2019envie de poursuivre la belle s\u00e9rie entam\u00e9e il y a cinq rencontres. Dans ce sprint final, Axel Disasi pense que l\u2019exp\u00e9rience de l\u2019ann\u00e9e pass\u00e9e peut servir \u00e0 l\u2019ASM : \u00ab *L\u2019ann\u00e9e derni\u00e8re nous avons v\u00e9cu un sprint final qui peut \u00eatre semblable \u00e0 cette fin de saison, mais les autres \u00e9quipes ont aussi leurs qualit\u00e9s, donc je pense que \u00e7a va \u00eatre excitant et int\u00e9ressant de voir qui tire son \u00e9pingle du jeu. En tout cas, nous allons tout faire pour que ce soit nous.* \u00bb<\/p>\n<p>Une belle s\u00e9rie qui doit beaucoup \u00e0 Philippe Clement, selon le d\u00e9fenseur central : \u00ab *Le coach nous a apport\u00e9 de la confiance. M\u00eame quand \u00e7a n\u2019allait pas, il \u00e9tait toujours l\u00e0, \u00e0 nous dire qu\u2019il fallait aller de l\u2019avant et inverser la spirale n\u00e9gative. La s\u00e9rie actuelle lui donne raison.* \u00bb Mais qui doit aussi \u00e0 l\u2019all\u00e9gement du calendrier : \u00ab *Il faut rappeler qu&rsquo;on \u00e9tait dans un calendrier qui nous faisait jouer tous les trois jours. Le fait d\u2019\u00eatre sorti de la Coupe d&rsquo;Europe a permis de travailler plus de choses, de se reposer plus, d&rsquo;arriver plus frais.* \u00bb<\/p>\n<p>Sur un plan individuel, Axel Disasi affiche un niveau bien meilleur et il s\u2019av\u00e8re assez satisfait : \u00ab *Au fur et \u00e0 mesure de la saison, je me suis senti de mieux en mieux, avec plus de confiance et de r\u00e9gularit\u00e9. D\u2019un point de vue personnel, je suis assez satisfait. Nous \u00e9voluons avec une d\u00e9fense \u00e0 quatre et nous avons eu le temps de plus travailler certains points tactiques, notamment les sorties de balles.* \u00bb<\/p>\n<p>L\u2019ancien joueur du Stade de Reims s\u2019est vu confi\u00e9 le vice-capitanat d\u00e8s son arriv\u00e9e et explique que cela lui a permis de se responsabiliser : \u00ab *Quand j&rsquo;ai eu ce r\u00f4le, lors des premiers matches, c&rsquo;\u00e9tait un peu nouveau pour moi, je ne savais pas ce que c&rsquo;\u00e9tait. J&rsquo;ai appris \u00e0 faire avec \u00e7a. J&rsquo;ai f\u00eat\u00e9 mes 24 ans. Par rapport au jeune groupe qu&rsquo;on a, je me devais de prendre ce r\u00f4le-l\u00e0 plus \u00e0 c\u0153ur et plus au s\u00e9rieux. \u00c7a me permet aussi de m&rsquo;\u00e9toffer sur d&rsquo;autres points.* \u00bb<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AS Monaco se d\u00e9place \u00e0 Saint-\u00c9tienne ce samedi avec l\u2019envie de poursuivre la belle s\u00e9rie entam\u00e9e il y a cinq rencontres. Dans ce sprint final, Axel Disasi pense que l\u2019exp\u00e9rience de l\u2019ann\u00e9e pass\u00e9e peut servir \u00e0 l\u2019ASM : \u00ab *L\u2019ann\u00e9e derni\u00e8re nous avons v\u00e9cu un sprint final qui peut \u00eatre semblable \u00e0 cette fin de [&#8230;]\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale\" \/>\n<meta property=\"og:description\" content=\"L\u2019AS Monaco se d\u00e9place \u00e0 Saint-\u00c9tienne ce samedi avec l\u2019envie de poursuivre la belle s\u00e9rie entam\u00e9e il y a cinq rencontres. Dans ce sprint final, Axel Disasi pense que l\u2019exp\u00e9rience de l\u2019ann\u00e9e pass\u00e9e peut servir \u00e0 l\u2019ASM : \u00ab *L\u2019ann\u00e9e derni\u00e8re nous avons v\u00e9cu un sprint final qui peut \u00eatre semblable \u00e0 cette fin de [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/\" \/>\n<meta property=\"og:site_name\" content=\"La Diagonale\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-22T17:07:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-26T12:20:28+00:00\" \/>\n<meta name=\"author\" content=\"Damien Dellerba\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Damien Dellerba\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/\",\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/\",\"name\":\"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale\",\"isPartOf\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#website\"},\"datePublished\":\"2022-04-22T17:07:57+00:00\",\"dateModified\":\"2022-07-26T12:20:28+00:00\",\"author\":{\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.ladiagonale.net\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.ladiagonale.net\/#website\",\"url\":\"https:\/\/www.ladiagonale.net\/\",\"name\":\"La Diagonale\",\"description\":\"Le site des supporters de l&#039;AS Monaco FC\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.ladiagonale.net\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf\",\"name\":\"Damien Dellerba\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g\",\"caption\":\"Damien Dellerba\"},\"url\":\"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/","og_locale":"fr_FR","og_type":"article","og_title":"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale","og_description":"L\u2019AS Monaco se d\u00e9place \u00e0 Saint-\u00c9tienne ce samedi avec l\u2019envie de poursuivre la belle s\u00e9rie entam\u00e9e il y a cinq rencontres. Dans ce sprint final, Axel Disasi pense que l\u2019exp\u00e9rience de l\u2019ann\u00e9e pass\u00e9e peut servir \u00e0 l\u2019ASM : \u00ab *L\u2019ann\u00e9e derni\u00e8re nous avons v\u00e9cu un sprint final qui peut \u00eatre semblable \u00e0 cette fin de [...]","og_url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/","og_site_name":"La Diagonale","article_published_time":"2022-04-22T17:07:57+00:00","article_modified_time":"2022-07-26T12:20:28+00:00","author":"Damien Dellerba","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Damien Dellerba","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/","url":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/","name":"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb - La Diagonale","isPartOf":{"@id":"https:\/\/www.ladiagonale.net\/#website"},"datePublished":"2022-04-22T17:07:57+00:00","dateModified":"2022-07-26T12:20:28+00:00","author":{"@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf"},"breadcrumb":{"@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.ladiagonale.net\/index.php\/2022\/04\/22\/disasi-notre-serie-donne-raison-au-coach\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.ladiagonale.net\/"},{"@type":"ListItem","position":2,"name":"Disasi : \u00ab Notre s\u00e9rie donne raison au coach \u00bb"}]},{"@type":"WebSite","@id":"https:\/\/www.ladiagonale.net\/#website","url":"https:\/\/www.ladiagonale.net\/","name":"La Diagonale","description":"Le site des supporters de l&#039;AS Monaco FC","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ladiagonale.net\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/79ff1e7b0853ed01b2aa26e64ad300bf","name":"Damien Dellerba","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.ladiagonale.net\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7850e06d3ff63cdbaee88b7fc16e2f0?s=96&d=mm&r=g","caption":"Damien Dellerba"},"url":"https:\/\/www.ladiagonale.net\/index.php\/author\/damien\/"}]}},"_links":{"self":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/992"}],"collection":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/comments?post=992"}],"version-history":[{"count":1,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/992\/revisions"}],"predecessor-version":[{"id":1822,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/posts\/992\/revisions\/1822"}],"wp:attachment":[{"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/media?parent=992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/categories?post=992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.ladiagonale.net\/index.php\/wp-json\/wp\/v2\/tags?post=992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}